{"id":5366,"date":"2026-07-15T08:16:00","date_gmt":"2026-07-15T06:16:00","guid":{"rendered":"https:\/\/www.fredonoccitanie.com\/eesh\/?p=5366"},"modified":"2026-07-15T11:03:10","modified_gmt":"2026-07-15T09:03:10","slug":"jeudi-23-juillet-reunion-dinformation-et-chantier-darrachage-a-rabouillet-66-2-2","status":"publish","type":"post","link":"https:\/\/www.fredonoccitanie.com\/eesh\/2026\/07\/15\/jeudi-23-juillet-reunion-dinformation-et-chantier-darrachage-a-rabouillet-66-2-2\/","title":{"rendered":"[LOZERE et ailleurs]\u00a0: Juillet, encore de nombreuses r\u00e9unions \u00e0 venir\u00a0!"},"content":{"rendered":"<p><strong>La lutte contre les ambroisies c\u2019est maintenant !<\/strong> et jusqu\u2019\u00e0 fin juillet pour les chantiers d\u2019arrachage.\u00a0 <strong>Les occasions de nous rencontrer sont encore nombreuses<\/strong> (<a href=\"https:\/\/www.fredonoccitanie.com\/eesh\/evenements\/\">consultez notre agenda<\/a>) :<\/p>\n<p>LOZERE\u00a0:<\/p>\n<ul>\n<li><strong>Gorges du Tarn Causses\u00a0: <\/strong>le vendredi <strong>17 juillet<\/strong> de 9h30 \u00e0 12h. Rendez-vous au camping La Chaden\u00e8de \/ co-organis\u00e9 avec le SMBVTarn-Amont<\/li>\n<li><strong>Saint-Martin-de-Lansuscle<\/strong>, le lundi <strong>20 juillet <\/strong>de 9h \u00e0 12h, dans le cadre de l\u2019ABC. Rendez-vous au temple<\/li>\n<li><strong>Malzieu-Ville, <\/strong>le mardi <strong>28 juillet <\/strong>de 10h \u00e0 12h30, avec la FDGDON de Loz\u00e8re. Rendez-vous \u00e0 la mairie du Malzieu-Ville<\/li>\n<li><strong>Altier,<\/strong> le mercredi <strong>29 juillet <\/strong>de 8h \u00e0 10h. Rendez-vous \u00e0 la mairie<\/li>\n<li><strong>Villefort<\/strong>, le mercredi <strong>29 juillet <\/strong>de 16h \u00e0 18h30. Rendez-vous \u00e0 la salle l\u2019Oustaou.<\/li>\n<li><strong>Villefort<\/strong>, le jeudi <strong>30 juillet <\/strong>de 8h \u00e0 12h. Venez nous rencontrer sur un stand au march\u00e9 de Villefort.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>GARD\u00a0:<\/p>\n<ul>\n<li><strong>Saint-Andr\u00e9-de-Majencoules,<\/strong> le jeudi <strong>16 juillet<\/strong> de 9h \u00e0 12h. Rendez-vous \u00e0 la mairie\u00a0; focus sur l\u2019ambroisie \u00e0 \u00e9pis lisses.<\/li>\n<li><strong>Dourbies,<\/strong> le jeudi <strong>16 juillet<\/strong> de 15h30 \u00e0 18h. Rendez-vous au hameau du Prunaret.<\/li>\n<li><strong>Chambon,<\/strong> le vendredi <strong>31 juillet <\/strong>de 9h \u00e0 12h. Rendez-vous \u00e0 la salle polyvalente<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>HERAULT\u00a0:<\/p>\n<ul>\n<li><strong>Aigues-Vives,<\/strong> le vendredi <strong>17 juillet<\/strong> de 18h \u00e0 20h, conf\u00e9rence et le samedi <strong>18 juillet <\/strong>de 8h \u00e0 10h30, chantier d\u2019arrachage. Rendez-vous \u00e0 la mairie.<\/li>\n<li><b>Agel, <\/b>le jeudi <b>23 Juillet <\/b>de 17h \u00e0 20h : stand de sensibilisation sur le march\u00e9 des producteurs<\/li>\n<li><strong>Le Caylar,<\/strong> les <strong>23 et 24 juillet<\/strong> de 9h \u00e0 12h, stand ambroisies au festival du Roc-Castel<\/li>\n<li><b>Agel, <\/b>le\u00a0samedi<b> 1er Ao\u00fbt\u00a0<\/b>de 8h \u00e0 10h30 : chantier d&rsquo;arrachage participatif<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>PYRENEES-ORIENTALES\u00a0:<\/p>\n<ul>\n<li><strong>Rabouillet<\/strong>, le jeudi <strong>23 juillet<\/strong> de 9h30 \u00e0 12h, en collaboration avec l\u2019ONF. Rendez-vous \u00e0 la mairie de Rabouillet ou \u00e0 Col-Bas \u00e0 10h. Attention, sous r\u00e9serve d\u2019accessibilit\u00e9 du massif\u00a0!<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>AUDE\u00a0:<\/p>\n<ul>\n<li><strong>Ginestas<\/strong> le mardi <strong>04 ao\u00fbt <\/strong>\u00e0 6h30. Rendez-vous \u00e0 la coop\u00e9rative viticole\u00a0; pr\u00e9sentation avec la FEDON11 lors des prospections flavescence dor\u00e9e.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La lutte contre les ambroisies c\u2019est maintenant ! et jusqu\u2019\u00e0 fin juillet pour les chantiers d\u2019arrachage.\u00a0 Les occasions de nous rencontrer sont encore nombreuses (consultez notre agenda) : LOZERE\u00a0: Gorges du Tarn Causses\u00a0: le vendredi 17 juillet de 9h30 \u00e0 12h. Rendez-vous au camping La Chaden\u00e8de \/ co-organis\u00e9 avec le SMBVTarn-Amont Saint-Martin-de-Lansuscle, le lundi 20 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5167,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,3],"tags":[],"class_list":["post-5366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-ambroisies","category-agenda-fredon"],"_links":{"self":[{"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/posts\/5366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/comments?post=5366"}],"version-history":[{"count":5,"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/posts\/5366\/revisions"}],"predecessor-version":[{"id":5400,"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/posts\/5366\/revisions\/5400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/media\/5167"}],"wp:attachment":[{"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/media?parent=5366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/categories?post=5366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fredonoccitanie.com\/eesh\/wp-json\/wp\/v2\/tags?post=5366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}